{"id":132,"count":0,"description":"","link":"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/","name":"Non class\u00e9","slug":"non-classe-es","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Archives des Non class\u00e9 - Mamba Blades<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Non class\u00e9 - Mamba Blades\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/\" \/>\n<meta property=\"og:site_name\" content=\"Mamba Blades\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/categoria-producto\\\/non-classe-es\\\/\",\"url\":\"https:\\\/\\\/mambablades.co\\\/es\\\/categoria-producto\\\/non-classe-es\\\/\",\"name\":\"Archives des Non class\u00e9 - Mamba Blades\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/categoria-producto\\\/non-classe-es\\\/#breadcrumb\"},\"inLanguage\":\"es\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/categoria-producto\\\/non-classe-es\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/mambablades.co\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Non class\u00e9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/mambablades.co\\\/es\\\/\",\"name\":\"Mamba Blades\",\"description\":\"Bois de Tennis de Table\",\"publisher\":{\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/mambablades.co\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/#organization\",\"name\":\"Mamba Blades\",\"url\":\"https:\\\/\\\/mambablades.co\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/mambablades.co\\\/MB\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo-Etsy.jpg\",\"contentUrl\":\"https:\\\/\\\/mambablades.co\\\/MB\\\/wp-content\\\/uploads\\\/2024\\\/11\\\/Logo-Etsy.jpg\",\"width\":200,\"height\":200,\"caption\":\"Mamba Blades\"},\"image\":{\"@id\":\"https:\\\/\\\/mambablades.co\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Non class\u00e9 - Mamba Blades","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/","og_locale":"es_ES","og_type":"article","og_title":"Archives des Non class\u00e9 - Mamba Blades","og_url":"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/","og_site_name":"Mamba Blades","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/","url":"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/","name":"Archives des Non class\u00e9 - Mamba Blades","isPartOf":{"@id":"https:\/\/mambablades.co\/es\/#website"},"breadcrumb":{"@id":"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/#breadcrumb"},"inLanguage":"es"},{"@type":"BreadcrumbList","@id":"https:\/\/mambablades.co\/es\/categoria-producto\/non-classe-es\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/mambablades.co\/es\/"},{"@type":"ListItem","position":2,"name":"Non class\u00e9"}]},{"@type":"WebSite","@id":"https:\/\/mambablades.co\/es\/#website","url":"https:\/\/mambablades.co\/es\/","name":"Mamba Blades","description":"Bois de Tennis de Table","publisher":{"@id":"https:\/\/mambablades.co\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/mambablades.co\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/mambablades.co\/es\/#organization","name":"Mamba Blades","url":"https:\/\/mambablades.co\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/mambablades.co\/es\/#\/schema\/logo\/image\/","url":"https:\/\/mambablades.co\/MB\/wp-content\/uploads\/2024\/11\/Logo-Etsy.jpg","contentUrl":"https:\/\/mambablades.co\/MB\/wp-content\/uploads\/2024\/11\/Logo-Etsy.jpg","width":200,"height":200,"caption":"Mamba Blades"},"image":{"@id":"https:\/\/mambablades.co\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/mambablades.co\/es\/wp-json\/wp\/v2\/product_cat\/132","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mambablades.co\/es\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/mambablades.co\/es\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/mambablades.co\/es\/wp-json\/wp\/v2\/product?product_cat=132"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}